{"id":4184,"date":"2022-07-20T15:42:16","date_gmt":"2022-07-20T15:42:16","guid":{"rendered":"https:\/\/aurelerossi.com\/?p=4184"},"modified":"2026-06-26T13:51:09","modified_gmt":"2026-06-26T11:51:09","slug":"sclerose-en-plaques","status":"publish","type":"post","link":"https:\/\/aurelerossi.com\/fr\/esclerosis-multiple\/","title":{"rendered":"Scl\u00e9rose en plaques et bienfaits de la chiropratique"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La <\/span><b>scl\u00e9rose en plaques<\/b> <b>C'est une maladie auto-immune chronique<\/b><span style=\"font-weight: 400;\">, ce qui affaiblit et affecte potentiellement le syst\u00e8me nerveux central, c'est-\u00e0-dire le cerveau, le tronc c\u00e9r\u00e9bral et la moelle \u00e9pini\u00e8re. La scl\u00e9rose en plaques touche plus de 2,5 millions de personnes dans le monde et environ 47 000 en Espagne. Il s\u2019agit d\u2019une maladie impr\u00e9visible, c\u2019est-\u00e0-dire dont la gravit\u00e9 varie, entra\u00eenant souvent un handicap important, mais qui peut parfois se manifester de mani\u00e8re b\u00e9nigne.\u00a0<\/span><\/p>\n<p>Dans cet article, vous apprendrez les informations suivantes sur la scl\u00e9rose en plaques :<\/p>\n<ul>\n<li>Les causes<\/li>\n<li>Comment la scl\u00e9rose en plaques affecte-t-elle le syst\u00e8me nerveux ?<\/li>\n<li>Les symptomes<\/li>\n<li>Evolution de la maladie<\/li>\n<li>La scl\u00e9rose en plaques et les traumatismes physiques comme facteurs environnementaux<\/li>\n<li>Chiropratique pour la scl\u00e9rose en plaques, prenez soin de votre colonne cervicale<\/li>\n<li>Relation entre la vitamine D et la scl\u00e9rose en plaques<\/li>\n<\/ul>\n<p><b>Cette maladie est \u00e9volutive,<\/b><span style=\"font-weight: 400\"> ce qui signifie que les l\u00e9sions nerveuses (neurod\u00e9g\u00e9n\u00e9rescence) s\u2019aggravent avec le temps. <\/span><b>On ne sait pas exactement pourquoi une personne d\u00e9veloppe la scl\u00e9rose en plaques.<\/b><span style=\"font-weight: 400\"> Autrement dit, la cause principale n\u2019a pas \u00e9t\u00e9 d\u00e9couverte et il n\u2019est pas clair si elle peut \u00eatre \u00e9vit\u00e9e. Ce que l'on sait jusqu'\u00e0 pr\u00e9sent sugg\u00e8re que cette maladie est caus\u00e9e par une combinaison de facteurs g\u00e9n\u00e9tiques et environnementaux, et ce sont quelques facteurs environnementaux dont nous parlerons dans cet article. Les premiers sympt\u00f4mes de la maladie apparaissent g\u00e9n\u00e9ralement entre 20 et 40 ans et la rapidit\u00e9 avec laquelle elle s\u2019aggrave varie d\u2019une personne \u00e0 l\u2019autre. Aujourd'hui, nous savons aussi que <\/span><b>l'incidence est deux fois plus \u00e9lev\u00e9e chez les femmes<\/b><span style=\"font-weight: 400\"> que chez les hommes.<\/span><\/p>\n<p><b>La scl\u00e9rose en plaques est une maladie auto-immune<\/b><span style=\"font-weight: 400\">, <\/span><b>ce qui signifie que le syst\u00e8me immunitaire prend une partie du corps pour une substance \u00e9trang\u00e8re et l'attaque, dans le cas de la scl\u00e9rose en plaques, il attaque le syst\u00e8me nerveux<\/b><span style=\"font-weight: 400\">. Et comment? Toutes les fibres nerveuses, qui transportent les impulsions \u00e9lectriques du cerveau et du tronc c\u00e9r\u00e9bral vers tous les tissus, sont entour\u00e9es d'une couche de protection adipeuse (graisse) qui facilite la conduction, cette couche est appel\u00e9e my\u00e9line. Sa fonction est d'entourer les nerfs, de les prot\u00e9ger et d'aider les signaux \u00e9lectriques \u00e0 se propager plus rapidement et plus efficacement. Ce sont pr\u00e9cis\u00e9ment ces cellules de my\u00e9line que notre syst\u00e8me immunitaire attaque et d\u00e9truit dans la scl\u00e9rose en plaques. Ce processus est \u00e9galement appel\u00e9, plus pr\u00e9cis\u00e9ment, processus de d\u00e9my\u00e9linisation nerveuse.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Nous expliquons en d\u00e9tail ci-dessous pour ceux qui souhaitent en savoir plus sur ce processus :<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les atteintes du syst\u00e8me nerveux provoquent une inflammation de la gaine de my\u00e9line, formant de petites taches (plaques ou l\u00e9sions), visibles en IRM. Ces plaques d\u2019inflammation peuvent perturber les messages qui circulent le long des nerfs. Cela peut ralentir le transit des informations, les envoyer de mani\u00e8re incorrecte ou m\u00eame les emp\u00eacher de transiter.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cette alt\u00e9ration conduit aux sympt\u00f4mes et signes caract\u00e9ristiques de la scl\u00e9rose en plaques, bien que <\/span><b>Ils peuvent \u00eatre tr\u00e8s diff\u00e9rents d\u2019une personne \u00e0 l\u2019autre.<\/b><span style=\"font-weight: 400\"> et au cours de l'\u00e9volution de la maladie en fonction de la localisation des fibres nerveuses touch\u00e9es. Ceux-ci pourraient \u00eatre :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><b>Engourdissement ou faiblesse dans une ou plusieurs extr\u00e9mit\u00e9s<\/b><span style=\"font-weight: 400\"> qui apparaissent normalement sur un c\u00f4t\u00e9 du corps \u00e0 la fois, ou sur les jambes et le tronc<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Perte de vision partielle ou totale<\/b><span style=\"font-weight: 400\">, g\u00e9n\u00e9ralement dans un \u0153il \u00e0 la fois, souvent accompagn\u00e9 de douleur lors du mouvement de l'\u0153il<\/span><\/li>\n<li><b>Vision double \u00e9tendue<\/b><\/li>\n<li><b>Des picotements ou des douleurs dans diff\u00e9rentes parties du corps<\/b><\/li>\n<li><b>Sensation de choc \u00e9lectrique<\/b><span style=\"font-weight: 400\"> qui se produit avec certains mouvements du cou, notamment lorsqu'on l'incline vers l'avant (signe de L'hermitte)<\/span><\/li>\n<li><b>Tremblements, manque de coordination ou d\u00e9marche instable<\/b><\/li>\n<li><b>Babillage<\/b><\/li>\n<li><b>Fatigue<\/b><\/li>\n<li><b>Vertiges<\/b><\/li>\n<li><b>Probl\u00e8mes de fonction intestinale et v\u00e9sicale<\/b><\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none\">\u00a0<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">La plupart des personnes atteintes de scl\u00e9rose en plaques ont <\/span><b>\u00e9volution r\u00e9mission-rechute de la maladie<\/b><span style=\"font-weight: 400\">. Ils ont des p\u00e9riodes de nouveaux sympt\u00f4mes ou de rechutes qui apparaissent au fil des jours ou des semaines et s'am\u00e9liorent g\u00e9n\u00e9ralement partiellement ou compl\u00e8tement. Ces rechutes sont suivies de p\u00e9riodes calmes de r\u00e9mission de la maladie qui peuvent durer des mois, voire des ann\u00e9es.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Depuis plus d\u2019un si\u00e8cle, m\u00e9decins et scientifiques tentent sans succ\u00e8s de d\u00e9terminer la cause exacte de la scl\u00e9rose en plaques. <\/span><b>Depuis des ann\u00e9es, la relation entre les traumatismes cr\u00e2niens et cervicals est \u00e9tudi\u00e9e comme un facteur possible.<\/b><span style=\"font-weight: 400\"> ce qui contribue \u00e9norm\u00e9ment \u00e0 l\u2019apparition et \u00e0 l\u2019\u00e9volution de la maladie. La raison de cette relation a \u00e9t\u00e9 trouv\u00e9e dans le fait qu'un traumatisme peut modifier la composition du liquide c\u00e9phalo-rachidien qui nourrit le syst\u00e8me nerveux, produisant des alt\u00e9rations de la barri\u00e8re qui prot\u00e8ge et s\u00e9pare le cerveau du reste du corps.<\/span><\/p>\n<p><span style=\"font-weight: 400\">L'expert renomm\u00e9, le Dr Charles Poser de la Harvard Medical School, a \u00e9galement conclu que <\/span><b>Les traumatismes \u00e0 la t\u00eate, au cou ou dans le haut du dos peuvent d\u00e9clencher l\u2019apparition de sympt\u00f4mes nouveaux ou r\u00e9currents chez certains patients atteints de scl\u00e9rose en plaques.<\/b><span style=\"font-weight: 400\">. Il est lui-m\u00eame all\u00e9 plus loin en pr\u00e9cisant que seuls les traumatismes touchant le cerveau et\/ou la moelle \u00e9pini\u00e8re peuvent \u00eatre consid\u00e9r\u00e9s comme significatifs, comme c'est le cas des coups du lapin ou des chutes avec traumatisme.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Apr\u00e8s tout, <\/span><b>Ces \u00e9tudes montrent que les traumatismes sont sans doute li\u00e9s \u00e0 l\u2019aggravation des sympt\u00f4mes et \u00e0 l\u2019apparition de la scl\u00e9rose en plaques.<\/b><span style=\"font-weight: 400\">. Cependant, <\/span><b>la cause d\u00e9finitive reste inconnue<\/b><span style=\"font-weight: 400\"> et est mieux compris comme la combinaison de facteurs de risque qui finiront par provoquer l'apparition et les sympt\u00f4mes de la scl\u00e9rose en plaques, qui peuvent prendre des jours, des mois, voire des ann\u00e9es, \u00e0 se d\u00e9velopper.<\/span><\/p>\n<p><b>Certaines des \u00e9tudes les plus innovantes et pertinentes en <span style=\"color: #0091b3;\"><a style=\"color: #0091b3;\" href=\"https:\/\/aurelerossi.com\/fr\/chiropratique-chiropratique-barcelone\/\">chiropractique<\/a><\/span> ont d\u00e9montr\u00e9 la relation entre la scl\u00e9rose en plaques et les blessures de la colonne cervicale sup\u00e9rieure<\/b><span style=\"font-weight: 400;\">. <\/span><b>Bien que les soins cervicaux ne soient pas consid\u00e9r\u00e9s comme un rem\u00e8de pour les personnes atteintes de scl\u00e9rose en plaques, des \u00e9tudes soutiennent les effets b\u00e9n\u00e9fiques observ\u00e9s apr\u00e8s avoir re\u00e7u des soins chiropratiques.<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La r\u00e9alit\u00e9 est que le chiropraticien est un sp\u00e9cialiste du soin et du bon fonctionnement du syst\u00e8me nerveux. Notre objectif est de stimuler et d'am\u00e9liorer la sant\u00e9 gr\u00e2ce \u00e0 des ajustements chiropratiques qui redonnent mobilit\u00e9 et vitalit\u00e9 au corps et \u00e0 l'ensemble de son m\u00e9tabolisme. <\/span><b>C\u2019est pour cette raison que ce sont pr\u00e9cis\u00e9ment les patients atteints de maladies neurod\u00e9g\u00e9n\u00e9ratives qui en b\u00e9n\u00e9ficient le plus et ressentent une grande am\u00e9lioration de leur qualit\u00e9 de vie.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Une \u00e9tude publi\u00e9e en 2005 a r\u00e9v\u00e9l\u00e9 la relation \u00e9troite entre des traumatismes ant\u00e9rieurs au cr\u00e2ne ou au cou et l'apparition de maladies neurod\u00e9g\u00e9n\u00e9ratives \u00e0 court ou \u00e0 long terme. Des preuves de cette relation ont \u00e9t\u00e9 trouv\u00e9es pour les deux <\/span><b>scl\u00e9rose en plaques<\/b><span style=\"font-weight: 400;\"> quant \u00e0 la maladie de <\/span><b>parkinson<\/b><span style=\"font-weight: 400;\">. <\/span><b>Cette m\u00eame \u00e9tude publi\u00e9e pr\u00e9sente des r\u00e9sultats qui d\u00e9montrent les avantages de la correction des blessures dans la partie sup\u00e9rieure du cou et d\u00e9montrent comment le processus d\u00e9g\u00e9n\u00e9ratif de la maladie peut \u00eatre invers\u00e9 et les sympt\u00f4mes att\u00e9nu\u00e9s gr\u00e2ce aux soins chiropratiques.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">L'\u00e9tude a \u00e9t\u00e9 men\u00e9e par le Dr Erin Elster, chiropracteur sp\u00e9cialis\u00e9 dans les soins des cervicales sup\u00e9rieures. Gr\u00e2ce aux soins des cervicales sup\u00e9rieures, Elster a corrig\u00e9 les l\u00e9sions cervicales chroniques subies par plus de 80 participants atteints de scl\u00e9rose en plaques et de Parkinson, et a obtenu une am\u00e9lioration de leurs sympt\u00f4mes et a pu r\u00e9duire le nombre de rechutes. Ces r\u00e9sultats ont \u00e9t\u00e9 reproduits dans d'autres centres de recherche sur les soins des cervicales sup\u00e9rieures, et les m\u00eames r\u00e9sultats positifs ont \u00e9t\u00e9 obtenus.<\/span><\/p>\n<p><b>Ce sont tous ces sympt\u00f4mes pour lesquels la chiropratique s\u2019est av\u00e9r\u00e9e b\u00e9n\u00e9fique :<\/b><\/p>\n<p><b>Insomnie, d\u00e9ficit cognitif, rigidit\u00e9, d\u00e9pression, engourdissement et faiblesse des extr\u00e9mit\u00e9s, fatigue, paralysie faciale, maux de t\u00eate<\/b><span style=\"font-weight: 400;\"> et plein d'autres.<\/span><\/p>\n<p><b>Nous pouvons donc conclure que les soins chiropratiques ont d\u2019\u00e9normes b\u00e9n\u00e9fices sur les sympt\u00f4mes dont souffrent les personnes atteintes de scl\u00e9rose en plaques<\/b><span style=\"font-weight: 400;\">. De plus, il retarde la d\u00e9t\u00e9rioration neurologique avec la progression de la maladie, allongeant les p\u00e9riodes de r\u00e9mission de crise et stabilisant et soignant le syst\u00e8me nerveux des patients qui consultent le chiropracteur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">On en parle souvent <\/span><b>Vitamine D<\/b><span style=\"font-weight: 400;\"> En tant que vitamine importante qui aide le corps \u00e0 rester en forme et fort, nous pouvons l'obtenir simplement par l'exposition au soleil, mais il s'av\u00e8re maintenant qu'elle pourrait \u00e9galement aider \u00e0 combattre les sympt\u00f4mes de la scl\u00e9rose en plaques. Bien que des recherches suppl\u00e9mentaires soient encore n\u00e9cessaires sur les effets b\u00e9n\u00e9fiques de la vitamine D, il y a certaines choses \u00e0 savoir sur sa relation avec la scl\u00e9rose en plaques.<\/span><\/p>\n<p class=\"translation-block\">Il existe des preuves sugg\u00e9rant que les personnes atteintes de scl\u00e9rose en plaques qui ont des niveaux plus \u00e9lev\u00e9s de vitamine D dans leur corps sont susceptibles de souffrir de sympt\u00f4mes moins graves. Selon une \u00e9tude r\u00e9alis\u00e9e sur sympt\u00f4mes chez un groupe de personnes atteintes de scl\u00e9rose en plaques, il a \u00e9t\u00e9 constat\u00e9 qu'apr\u00e8s cinq ans plus tard, ceux ayant des niveaux plus \u00e9lev\u00e9s de vitamine D ont connu moins de probl\u00e8mes. Bien que cette d\u00e9couverte soit prometteuse, des recherches suppl\u00e9mentaires sont n\u00e9cessaires pour d\u00e9terminer si la vitamine D peut ralentir ou non la progression de la scl\u00e9rose en plaques.<\/p>\n<p><span style=\"font-weight: 400;\">D'autres \u00e9tudes ont montr\u00e9 que la vitamine D pourrait \u00eatre utile dans la pr\u00e9vention de la maladie. Les chercheurs ont d\u00e9couvert que les enfants qui passaient beaucoup de temps au soleil \u00e9taient moins susceptibles de d\u00e9velopper la maladie plus tard dans leur vie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cela se refl\u00e8te \u00e9galement dans le fait que plus on vit loin de l'\u00e9quateur, plus le risque de d\u00e9velopper la scl\u00e9rose en plaques est grand, puisque la quantit\u00e9 de lumi\u00e8re solaire diminue, donc dans les pays nordiques l'incidence est plus \u00e9lev\u00e9e puisque le d\u00e9ficit fonctionne comme un facteur environnemental. C'est ainsi que des \u00e9tudes men\u00e9es chez des femmes finlandaises, bien moins expos\u00e9es au soleil et pr\u00e9sentant historiquement de faibles niveaux de vitamine D, montrent qu'il existe un risque 43 % plus \u00e9lev\u00e9 de d\u00e9velopper une scl\u00e9rose en plaques en cas de carence prolong\u00e9e en vitamine D.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c0 ce jour, personne ne sait vraiment quel r\u00f4le joue la vitamine D dans la protection contre la scl\u00e9rose en plaques. Beaucoup pensent que la vitamine D am\u00e9liore le syst\u00e8me immunitaire, ce qui rend une personne moins susceptible de d\u00e9velopper une maladie auto-immune telle que la scl\u00e9rose en plaques.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un simple test sanguin peut d\u00e9terminer votre taux de vitamine D. La National Multiple Sclerosis Society sugg\u00e8re que les personnes vivant avec la maladie devraient recevoir entre 200 et 600 UI (unit\u00e9s internationales) par jour.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tu peux passer <\/span><b>15 minutes par jour au soleil, ou prendre une suppl\u00e9mentation en vitamines<\/b><span style=\"font-weight: 400;\"> (si recommand\u00e9 par votre \u00e9quipe soignante) ou <\/span><b>Mangez plus d'aliments contenant de la vitamine D, comme les poissons gras, le foie de b\u0153uf, le fromage, les \u0153ufs et les aliments enrichis en vitamine D, comme les c\u00e9r\u00e9ales, le lait et le jus d'orange.<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Il faut tenir compte du fait que des doses \u00e9lev\u00e9es peuvent \u00e9galement entra\u00eener des modifications des niveaux de calcium dans l'organisme, c'est pourquoi il est recommand\u00e9 de toujours prendre de la vitamine K avec de la vitamine D, qui sera responsable de l'\u00e9quilibre de votre syst\u00e8me.<\/span><\/p>\n<p><strong>Si vous souffrez de scl\u00e9rose en plaques ou de sympt\u00f4mes associ\u00e9s, nous vous recommandons de consulter un chiropracteur.<\/strong>.<\/p>\n<p>En Espagne, si vous recherchez un chiropracteur, v\u00e9rifiez qu'il est membre de la<span style=\"color: #000000;\">\u00a0<a style=\"color: #000000;\" href=\"https:\/\/quiropractica-aeq.com\/buscador-registro-socios\/\" target=\"_blank\" rel=\"noopener\">Asociaci\u00f3n Espa\u00f1ola de Quiropr\u00e1ctica<\/a><\/span> (AEQ), qui regroupe exclusivement des dipl\u00f4m\u00e9s en Chiropratique titulaires d'un dipl\u00f4me universitaire d\u00e9livr\u00e9 par une des universit\u00e9s de Chiropratique reconnues par le Conseil Europ\u00e9en de l'Enseignement Chiropratique.<\/p>","protected":false},"excerpt":{"rendered":"<p>La esclerosis m\u00faltiple es una enfermedad autoinmune cr\u00f3nica, que potencialmente debilita y afecta al sistema nervioso central, es decir el cerebro, el tallo encef\u00e1lico y la m\u00e9dula espinal. La esclerosis m\u00faltiple afecta a m\u00e1s de 2.5 millones de personas en el mundo y unas 47.000 en Espa\u00f1a. Es una enfermedad impredecible, es decir que var\u00eda [&hellip;]<\/p>","protected":false},"author":2,"featured_media":7715,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[37,78,73],"class_list":["post-4184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quiropractica","tag-esclerosis-multiple","tag-quiropractica","tag-quiropractico-2"],"_links":{"self":[{"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/posts\/4184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/comments?post=4184"}],"version-history":[{"count":2,"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/posts\/4184\/revisions"}],"predecessor-version":[{"id":13620,"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/posts\/4184\/revisions\/13620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/media\/7715"}],"wp:attachment":[{"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/media?parent=4184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/categories?post=4184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aurelerossi.com\/fr\/wp-json\/wp\/v2\/tags?post=4184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}